{"id":2442,"date":"2019-05-22T11:18:01","date_gmt":"2019-05-22T16:18:01","guid":{"rendered":"http:\/\/adc.org.co\/?page_id=2442"},"modified":"2019-05-22T11:18:01","modified_gmt":"2019-05-22T16:18:01","slug":"ing-especialista-diseno-estructural","status":"publish","type":"page","link":"https:\/\/adc.org.co\/en\/ing-especialista-diseno-estructural\/","title":{"rendered":"Ing. Especialista en Dise\u00f1o Estructural"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2381 size-full\" src=\"http:\/\/adc.org.co\/wp-content\/uploads\/2019\/04\/Captura-de-pantalla-2019-04-01-a-las-3.36.16-p.m..png\" alt=\"\" width=\"1137\" height=\"126\" srcset=\"https:\/\/adc.org.co\/wp-content\/uploads\/2019\/04\/Captura-de-pantalla-2019-04-01-a-las-3.36.16-p.m..png 1137w, https:\/\/adc.org.co\/wp-content\/uploads\/2019\/04\/Captura-de-pantalla-2019-04-01-a-las-3.36.16-p.m.-300x33.png 300w, https:\/\/adc.org.co\/wp-content\/uploads\/2019\/04\/Captura-de-pantalla-2019-04-01-a-las-3.36.16-p.m.-768x85.png 768w, https:\/\/adc.org.co\/wp-content\/uploads\/2019\/04\/Captura-de-pantalla-2019-04-01-a-las-3.36.16-p.m.-1024x113.png 1024w, https:\/\/adc.org.co\/wp-content\/uploads\/2019\/04\/Captura-de-pantalla-2019-04-01-a-las-3.36.16-p.m.-880x98.png 880w, https:\/\/adc.org.co\/wp-content\/uploads\/2019\/04\/Captura-de-pantalla-2019-04-01-a-las-3.36.16-p.m.-450x50.png 450w\" sizes=\"auto, (max-width: 1137px) 100vw, 1137px\" \/><\/p>\n<p class=\"m_-3632534128658945649gmail-m_-5723695753928972446gmail-m_-4855500674242793944gmail-m_-2149020391178930975gmail-m_6043438020047257623m_664952339105619034gmail-p2\" style=\"text-align: center;\"><strong>PROYECTO DE DESARROLLO TERRITORIAL EN EL DEPARTAMENTO DE NARI\u00d1O EN CONDICIONES DE PAZ. PDT &#8211; NARI\u00d1O<\/strong><\/p>\n<p class=\"m_-3632534128658945649gmail-m_-5723695753928972446gmail-m_-4855500674242793944gmail-m_-2149020391178930975gmail-m_6043438020047257623m_664952339105619034gmail-p2\"><strong>CONVOCATORIA ABIERTA:<\/strong><\/p>\n<h3>Profesionales para el dise\u00f1o estructural en la Unidad de Proyectos del Plan Departamental de Agua, PDA \u2013 Gobernaci\u00f3n de Nari\u00f1o.<\/h3>\n<p class=\"m_-3632534128658945649gmail-m_-5723695753928972446gmail-m_-4855500674242793944gmail-m_-2149020391178930975gmail-m_6043438020047257623m_664952339105619034gmail-p2\"><span class=\"im\"><strong>Fecha de publicaci\u00f3n:<\/strong> 22 de mayo de 2019.<br \/>\n<strong>Fecha l\u00edmite de recepci\u00f3n de propuestas:<\/strong>\u00a005 de junio de 2019.<br \/>\n<\/span><strong>Modalidad de contrataci\u00f3n:\u00a0<\/strong>Prestaci\u00f3n de Servicios Profesionales.\u00a0<span class=\"im\"><br \/>\n<strong>Entidad contratante:<\/strong>\u00a0Asociaci\u00f3n para el Desarrollo Campesino \u2013 ADC.<\/span><\/p>\n<p><a href=\"http:\/\/adc.org.co\/wp-content\/uploads\/2019\/05\/T18-2019-014-ING.-ESPECIALISTA-EN-DISEN\u0303O-ESTRUCTURAL.pdf\" target=\"_blank\" rel=\"noopener\">Acceda al TDR haciendo click aqu\u00ed<\/a><\/p>\n<p class=\"m_-3632534128658945649gmail-m_-5723695753928972446gmail-m_-4855500674242793944gmail-m_-2149020391178930975gmail-m_6043438020047257623m_664952339105619034gmail-p2\">Las personas interesadas que cumplan los requisitos pueden enviar la hoja de vida al siguiente correo:\u00a0<span class=\"m_-3632534128658945649gmail-m_-5723695753928972446gmail-m_-4855500674242793944gmail-m_-2149020391178930975gmail-m_6043438020047257623m_664952339105619034gmail-s2\"><a href=\"mailto:talentohumanopdt@gmail.com\" target=\"_blank\" rel=\"noopener\">talentohumanopdt@<wbr \/>gmail.com<\/a>.<\/span><\/p>\n<p class=\"m_-3632534128658945649gmail-m_-5723695753928972446gmail-m_-4855500674242793944gmail-m_-2149020391178930975gmail-m_6043438020047257623m_664952339105619034gmail-p2\"><strong>Fecha de Cierre de la Convocatoria:\u00a0<\/strong>05 de mayo de 2019 a las 18:00h<\/p>\n<div>\n<div>La Asociaci\u00f3n para el Desarrollo Campesino \u2013 ADC en el marco del\u00a0 Proyecto de Desarrollo Territorial en el Departamento de Nari\u00f1o en Condiciones de Paz PDT Nari\u00f1o con el financiamiento de la Uni\u00f3n Europea a trav\u00e9s del Fondo Europeo para la Paz de Colombia y la Agencia Espa\u00f1ola de Cooperaci\u00f3n Internacional para el Desarrollo AECID, desea contratar al siguiente personal de apoyo.<\/div>\n<\/div>\n<div>\n<div><\/div>\n<\/div>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-2380 size-full\" src=\"http:\/\/adc.org.co\/wp-content\/uploads\/2019\/04\/Captura-de-pantalla-2019-04-01-a-las-3.36.23-p.m..png\" alt=\"\" width=\"1041\" height=\"142\" srcset=\"https:\/\/adc.org.co\/wp-content\/uploads\/2019\/04\/Captura-de-pantalla-2019-04-01-a-las-3.36.23-p.m..png 1041w, https:\/\/adc.org.co\/wp-content\/uploads\/2019\/04\/Captura-de-pantalla-2019-04-01-a-las-3.36.23-p.m.-300x41.png 300w, https:\/\/adc.org.co\/wp-content\/uploads\/2019\/04\/Captura-de-pantalla-2019-04-01-a-las-3.36.23-p.m.-768x105.png 768w, https:\/\/adc.org.co\/wp-content\/uploads\/2019\/04\/Captura-de-pantalla-2019-04-01-a-las-3.36.23-p.m.-1024x140.png 1024w, https:\/\/adc.org.co\/wp-content\/uploads\/2019\/04\/Captura-de-pantalla-2019-04-01-a-las-3.36.23-p.m.-880x120.png 880w, https:\/\/adc.org.co\/wp-content\/uploads\/2019\/04\/Captura-de-pantalla-2019-04-01-a-las-3.36.23-p.m.-450x61.png 450w\" sizes=\"auto, (max-width: 1041px) 100vw, 1041px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>PROYECTO DE DESARROLLO TERRITORIAL EN EL DEPARTAMENTO DE NARI\u00d1O EN CONDICIONES DE PAZ. PDT &#8211; NARI\u00d1O CONVOCATORIA ABIERTA: Profesionales para el dise\u00f1o estructural en la Unidad de Proyectos del Plan Departamental de Agua, PDA \u2013 Gobernaci\u00f3n de Nari\u00f1o. Fecha de publicaci\u00f3n: 22 de mayo de 2019. Fecha l\u00edmite de recepci\u00f3n de propuestas:\u00a005 de junio de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2442","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/adc.org.co\/en\/wp-json\/wp\/v2\/pages\/2442","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adc.org.co\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/adc.org.co\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/adc.org.co\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/adc.org.co\/en\/wp-json\/wp\/v2\/comments?post=2442"}],"version-history":[{"count":1,"href":"https:\/\/adc.org.co\/en\/wp-json\/wp\/v2\/pages\/2442\/revisions"}],"predecessor-version":[{"id":2445,"href":"https:\/\/adc.org.co\/en\/wp-json\/wp\/v2\/pages\/2442\/revisions\/2445"}],"wp:attachment":[{"href":"https:\/\/adc.org.co\/en\/wp-json\/wp\/v2\/media?parent=2442"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}